{"id":993,"date":"2020-02-13T13:06:31","date_gmt":"2020-02-13T13:06:31","guid":{"rendered":"https:\/\/sges.co.in\/index.php\/services\/"},"modified":"2025-08-04T17:31:12","modified_gmt":"2025-08-04T17:31:12","slug":"services","status":"publish","type":"page","link":"https:\/\/sges.co.in\/index.php\/services\/","title":{"rendered":"Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"993\" class=\"elementor elementor-993\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e215091 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e215091\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2ce682\" data-id=\"b2ce682\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2659b8e img-align-tablet-top image-vertical-align-center slide-h-position-tablet-center icon-box-vertical-align-top img-align-left preserve-img-ratio-cover slide-h-position-left elementor-widget elementor-widget-the7-elements-simple-posts\" data-id=\"2659b8e\" data-element_type=\"widget\" data-widget_type=\"the7-elements-simple-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"the7-simple-widget-posts the7-elementor-widget the7-elements-simple-posts-2659b8e jquery-filter jquery-filter\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-scroll-offset=\"\" aria-live=\"assertive\">\t\t\t<div class=\"dt-css-grid custom-pagination-handler\" data-columns=\"{&quot;d&quot;:2,&quot;t&quot;:2,&quot;p&quot;:1,&quot;wd&quot;:&quot;&quot;}\">\n\t\t\t\t\t\t\t\t\t<div class=\"wf-cell visible \">\n\t\t\t\t\t\t<article class=\"post visible wrapper post-2917 our_services type-our_services status-publish has-post-thumbnail hentry\">\n\n\t\t\t\t\t\t\t<div class=\"post-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"the7-simple-post-thumb\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiaccouting\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%201000&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 1000;\" data-src=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1.jpg\" loading=\"eager\" data-srcset=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1.jpg 1500w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1-300x200.jpg 300w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1-1024x683.jpg 1024w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1-768x512.jpg 768w\" \/><span class=\"the7-hover-icon\"><\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-entry-content\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"heading\"><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiaccouting\/\" rel=\"bookmark\" title=\"Digi Accounting\" class=\"post-title\">Digi Accounting<\/a><\/h4><p class=\"short-description\">DigiAccounting is a web-based application simplifying accounting tasks, offering easy financial management, reporting, and bookkeeping for businesses and professionals.\n <\/p><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiaccouting\/\" target=\"\" aria-label=\"Read more about Digi Accounting\" class=\"box-button elementor-button elementor-size-sm\">Details<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\t<div class=\"wf-cell visible \">\n\t\t\t\t\t\t<article class=\"post visible wrapper post-2899 our_services type-our_services status-publish has-post-thumbnail hentry\">\n\n\t\t\t\t\t\t\t<div class=\"post-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"the7-simple-post-thumb\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/sges.co.in\/index.php\/our_services\/digicrusher\/\"><img decoding=\"async\" width=\"1500\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%201000&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 1000;\" data-src=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/01\/img001-8-1.jpg\" loading=\"eager\" data-srcset=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/01\/img001-8-1.jpg 1500w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/01\/img001-8-1-300x200.jpg 300w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/01\/img001-8-1-1024x683.jpg 1024w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/01\/img001-8-1-768x512.jpg 768w\" \/><span class=\"the7-hover-icon\"><\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-entry-content\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"heading\"><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digicrusher\/\" rel=\"bookmark\" title=\"Digi Crusher\" class=\"post-title\">Digi Crusher<\/a><\/h4><p class=\"short-description\">DigiCrushing is a web application that enables crushers to manage transactions digitally, track operations, and streamline business processes efficiently.<\/p><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digicrusher\/\" target=\"\" aria-label=\"Read more about Digi Crusher\" class=\"box-button elementor-button elementor-size-sm\">Details<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\t<div class=\"wf-cell visible \">\n\t\t\t\t\t\t<article class=\"post visible wrapper post-24893 our_services type-our_services status-publish has-post-thumbnail hentry\">\n\n\t\t\t\t\t\t\t<div class=\"post-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"the7-simple-post-thumb\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiminer\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%201000&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 1000;\" data-src=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1.jpg\" loading=\"eager\" data-srcset=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1.jpg 1500w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1-300x200.jpg 300w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1-1024x683.jpg 1024w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-1-1-768x512.jpg 768w\" \/><span class=\"the7-hover-icon\"><\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-entry-content\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"heading\"><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiminer\/\" rel=\"bookmark\" title=\"Digi Miner\" class=\"post-title\">Digi Miner<\/a><\/h4><p class=\"short-description\">DigiMiner helps miners efficiently manage transactions, track operational data, and maintain digital records, reducing manual effort and improving accuracy in mining operations.<\/p><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiminer\/\" target=\"\" aria-label=\"Read more about Digi Miner\" class=\"box-button elementor-button elementor-size-sm\">Details<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\t<div class=\"wf-cell visible \">\n\t\t\t\t\t\t<article class=\"post visible wrapper post-2883 our_services type-our_services status-publish has-post-thumbnail hentry\">\n\n\t\t\t\t\t\t\t<div class=\"post-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"the7-simple-post-thumb\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiproduction\/\"><img decoding=\"async\" width=\"1500\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%201000&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 1000;\" data-src=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-25-1.jpg\" loading=\"eager\" data-srcset=\"https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-25-1.jpg 1500w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-25-1-300x200.jpg 300w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-25-1-1024x683.jpg 1024w, https:\/\/sges.co.in\/wp-content\/uploads\/2020\/02\/img001-25-1-768x512.jpg 768w\" \/><span class=\"the7-hover-icon\"><\/span><\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-entry-content\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"heading\"><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiproduction\/\" rel=\"bookmark\" title=\"Digi Production\" class=\"post-title\">Digi Production<\/a><\/h4><p class=\"short-description\">DigiProduction is a web application that helps manufacturers manage production data digitally, track operations, optimize workflows, and enhance efficiency.<\/p><a href=\"https:\/\/sges.co.in\/index.php\/our_services\/digiproduction\/\" target=\"\" aria-label=\"Read more about Digi Production\" class=\"box-button elementor-button elementor-size-sm\">Details<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ae2e86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ae2e86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-710e4da\" data-id=\"710e4da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-851f5b5 elementor-widget elementor-widget-heading\" data-id=\"851f5b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principles of our work<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c5e932 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c5e932\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f5036b\" data-id=\"4f5036b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c99eb9 elementor-widget elementor-widget-heading\" data-id=\"8c99eb9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">01.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bcfc5d elementor-widget elementor-widget-spacer\" data-id=\"2bcfc5d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82d8684 elementor-widget elementor-widget-heading\" data-id=\"82d8684\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quality<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1b694b elementor-widget elementor-widget-spacer\" data-id=\"f1b694b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b89a739 elementor-widget elementor-widget-text-editor\" data-id=\"b89a739\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nullam arcu felis, tristique eget malesuada sed, viverra at sapien. Maecenas gravida lacus nec dolor suscipit faucibus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d168b13\" data-id=\"d168b13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23a67e9 elementor-widget elementor-widget-heading\" data-id=\"23a67e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">02.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-246ab1a elementor-widget elementor-widget-spacer\" data-id=\"246ab1a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69f4e0d elementor-widget elementor-widget-heading\" data-id=\"69f4e0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Integrity<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abaae9c elementor-widget elementor-widget-spacer\" data-id=\"abaae9c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddfc823 elementor-widget elementor-widget-text-editor\" data-id=\"ddfc823\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTristique eget malesuada sed arcu felis, viverra viverra at sapien at sapien. Maecenas gravida lacus nec dolor suscipit faucibus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ec22cf3\" data-id=\"ec22cf3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24090e2 elementor-widget elementor-widget-heading\" data-id=\"24090e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">03.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce6ac00 elementor-widget elementor-widget-spacer\" data-id=\"ce6ac00\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8ef148 elementor-widget elementor-widget-heading\" data-id=\"a8ef148\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Innovations<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3ba778 elementor-widget elementor-widget-spacer\" data-id=\"a3ba778\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b4b4f elementor-widget elementor-widget-text-editor\" data-id=\"77b4b4f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nunc ut \u2013 for dictum purus lorem vel ante ac purus sollicitudin dictum ipsum eget ex convallis from dolor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a21e3c elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9a21e3c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fd603a2\" data-id=\"fd603a2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61909c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61909c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d6d8a49\" data-id=\"d6d8a49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23774f2 elementor-widget elementor-widget-heading\" data-id=\"23774f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Not sure what fits your business needs? Get free consultation!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae8100b elementor-widget elementor-widget-spacer\" data-id=\"ae8100b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b95070 elementor-widget elementor-widget-text-editor\" data-id=\"0b95070\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Experience you can trust, service you can count on. Seven Company &#8211; your partners in profit!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdfd26d elementor-widget elementor-widget-spacer\" data-id=\"cdfd26d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-136c5d2 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"136c5d2\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"993\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"136c5d2\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Services\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"993\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_600c39e elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_600c39e\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPhone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_600c39e]\" id=\"form-field-field_600c39e\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request a call-back<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-caae64b elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"caae64b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fff5c2d elementor-widget elementor-widget-spacer\" data-id=\"fff5c2d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Digi Accounting Ut sit amet semper arcu. Proin eget ex viverra lorem pretium. Morbi dapibus a tellus at euismod. Ut sit amet semper! Details Digi Crusher Ut sit amet semper arcu. Proin eget ex convallis eu viverra lorem pretium. Morbi dapibus a tellus. Details Digi Miner Ut sit amet semper arcu. Proin eget ex viverra&hellip;<\/p>\n","protected":false},"author":1,"featured_media":455,"parent":0,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-993","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/pages\/993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/comments?post=993"}],"version-history":[{"count":3,"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/pages\/993\/revisions"}],"predecessor-version":[{"id":25207,"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/pages\/993\/revisions\/25207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/media\/455"}],"wp:attachment":[{"href":"https:\/\/sges.co.in\/index.php\/wp-json\/wp\/v2\/media?parent=993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}